{"id":134,"count":6,"description":"<strong>PSV<\/strong> \u2018s range of <strong>band saws<\/strong> is made entirely from 304 stainless steel, making these robust machines long-lasting and easy to clean and maintain. These are <strong>professional<\/strong> machines with high output and large cutting capacity for their size. They allow you to work safely and precisely in all the sectors for which these machines are designed, i.e. the cutting of bands and fresh or frozen <strong>meat<\/strong>, fish and other products....\r\n\r\nTable-top or floor-standing machines, depending on model and capacity.\r\n\r\nWe offer a wide range to suit all requirements.\r\n\r\nThe motorisation is particularly suited to power requirements, and the electromechanical controls are particularly reliable.\r\n\r\nQuality blade with tensioning system and scrapers that can be removed without tools.","link":"https:\/\/psv-groupe.com\/en\/families\/band-saws\/","name":"BAND SAWS","slug":"band-saws","taxonomy":"familles","parent":0,"meta":{"visuel-famille-produits":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scies \u00e0 os professionnelles PSV<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre large gamme de scies \u00e0 os, disponibles sur table et sur socle dot\u00e9es d&#039;une grande pr\u00e9cision et capacit\u00e9 de coupe.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scies \u00e0 os professionnelles PSV\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre large gamme de scies \u00e0 os, disponibles sur table et sur socle dot\u00e9es d&#039;une grande pr\u00e9cision et capacit\u00e9 de coupe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/psv-groupe.com\/en\/families\/band-saws\/\" \/>\n<meta property=\"og:site_name\" content=\"PSV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/families\\\/band-saws\\\/\",\"url\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/families\\\/band-saws\\\/\",\"name\":\"Scies \u00e0 os professionnelles PSV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/#website\"},\"description\":\"D\u00e9couvrez notre large gamme de scies \u00e0 os, disponibles sur table et sur socle dot\u00e9es d'une grande pr\u00e9cision et capacit\u00e9 de coupe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/families\\\/band-saws\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/families\\\/band-saws\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAND SAWS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/\",\"name\":\"PSV\",\"description\":\"Fabricants de machines haut de gamme pour l\u2019artisanat et l\u2019industrie alimentaire.\",\"publisher\":{\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/#organization\",\"name\":\"PSV\",\"url\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/psv-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/LOGO-ENG-1.png\",\"contentUrl\":\"https:\\\/\\\/psv-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/LOGO-ENG-1.png\",\"width\":828,\"height\":484,\"caption\":\"PSV\"},\"image\":{\"@id\":\"https:\\\/\\\/psv-groupe.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scies \u00e0 os professionnelles PSV","description":"D\u00e9couvrez notre large gamme de scies \u00e0 os, disponibles sur table et sur socle dot\u00e9es d'une grande pr\u00e9cision et capacit\u00e9 de coupe.","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Scies \u00e0 os professionnelles PSV","og_description":"D\u00e9couvrez notre large gamme de scies \u00e0 os, disponibles sur table et sur socle dot\u00e9es d'une grande pr\u00e9cision et capacit\u00e9 de coupe.","og_url":"https:\/\/psv-groupe.com\/en\/families\/band-saws\/","og_site_name":"PSV","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/psv-groupe.com\/en\/families\/band-saws\/","url":"https:\/\/psv-groupe.com\/en\/families\/band-saws\/","name":"Scies \u00e0 os professionnelles PSV","isPartOf":{"@id":"https:\/\/psv-groupe.com\/en\/#website"},"description":"D\u00e9couvrez notre large gamme de scies \u00e0 os, disponibles sur table et sur socle dot\u00e9es d'une grande pr\u00e9cision et capacit\u00e9 de coupe.","breadcrumb":{"@id":"https:\/\/psv-groupe.com\/en\/families\/band-saws\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/psv-groupe.com\/en\/families\/band-saws\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/psv-groupe.com\/en\/"},{"@type":"ListItem","position":2,"name":"BAND SAWS"}]},{"@type":"WebSite","@id":"https:\/\/psv-groupe.com\/en\/#website","url":"https:\/\/psv-groupe.com\/en\/","name":"PSV","description":"Fabricants de machines haut de gamme pour l\u2019artisanat et l\u2019industrie alimentaire.","publisher":{"@id":"https:\/\/psv-groupe.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/psv-groupe.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/psv-groupe.com\/en\/#organization","name":"PSV","url":"https:\/\/psv-groupe.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/psv-groupe.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/psv-groupe.com\/wp-content\/uploads\/2022\/03\/LOGO-ENG-1.png","contentUrl":"https:\/\/psv-groupe.com\/wp-content\/uploads\/2022\/03\/LOGO-ENG-1.png","width":828,"height":484,"caption":"PSV"},"image":{"@id":"https:\/\/psv-groupe.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/psv-groupe.com\/en\/wp-json\/wp\/v2\/familles\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psv-groupe.com\/en\/wp-json\/wp\/v2\/familles"}],"about":[{"href":"https:\/\/psv-groupe.com\/en\/wp-json\/wp\/v2\/taxonomies\/familles"}],"wp:post_type":[{"href":"https:\/\/psv-groupe.com\/en\/wp-json\/wp\/v2\/produits_psv?familles=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}